{"id":124084,"date":"2023-06-24T09:43:45","date_gmt":"2023-06-24T07:43:45","guid":{"rendered":"https:\/\/upmp.news\/?p=124084"},"modified":"2023-07-04T13:14:07","modified_gmt":"2023-07-04T11:14:07","slug":"strong-fake-drogenabhangige-soldaten-der-us-armee-die-aus-der-armee-entlassen-wurden-kampfen-nun-auf-der-seite-der-ukraine-strong","status":"publish","type":"post","link":"https:\/\/upmp.news\/de\/stop-lie-spezialprojekt\/strong-fake-drogenabhangige-soldaten-der-us-armee-die-aus-der-armee-entlassen-wurden-kampfen-nun-auf-der-seite-der-ukraine-strong\/","title":{"rendered":"<strong>Fake: Drogenabh\u00e4ngige Soldaten der US-Armee, die aus der Armee entlassen wurden, k\u00e4mpfen nun auf der Seite der Ukraine<\/strong>"},"content":{"rendered":"\n<p><strong>Der polnischsprachige Telegram-Kanal der Internetpublikation <a href=\"https:\/\/oko.press\/portal-z-falszywkami-kradnie-artykuly-tak-uwiarygodnia-sie-rosyjska-dezinformacja-w-polsce\">Niezale\u017cny Dziennik Polityczny<\/a>, bekannt f\u00fcr die st\u00e4ndige Verbreitung von Fakes und russischen Propagandainhalten, ver\u00f6ffentlichte einen Artikel mit dem Titel \u201eDrogenabh\u00e4ngige aus der Armee entlassene US-Soldaten k\u00e4mpfen jetzt auf der Seite der Ukraine\u201c (\u00abUzale\u017cnieni od narkotyk\u00f3w \u017co\u0142nierze US Army zwolnieni z wojska walcz\u0105 teraz po stronie Ukrainy\u00bb).<\/strong><\/p>\n\n\n\n<p>Der Text nutzt die von den Russen oft angewandte Technik, um die K\u00e4mpfer der Internationalen Legion von der Territorialen Verteidigung der Streitkr\u00e4fte der Ukraine, wo die Freiwillige \u2013 B\u00fcrger anderer L\u00e4nder \u2013 dienen, zu entmenschlichen und zu diskreditieren.<\/p>\n\n\n\n<p>Hierzu wird auf die angeblich gro\u00dfe Zahl amerikanischer Soldaten hingewiesen, die innerhalb von zwei Jahren wegen Drogenkonsums entlassen wurden, \u201evon denen ein gro\u00dfer Teil nach Beginn des Konflikts in der Ukraine als S\u00f6ldner in die Streitkr\u00e4fte eingetreten ist\u201c. Offenbar in Bezug auf das ukrainische Milit\u00e4r werden ihren amerikanischen Partnern Pl\u00fcnderungen, unangemessenes Verhalten und die Tatsache vorgeworfen, dass sie vom Westen bereitgestellte Waffen von Ukrainern klauen und weiterverkaufen.<\/p>\n\n\n\n<p>Die Herkunft dieser F\u00e4lschung ist leicht zu ermitteln \u2013 derselbe Text erschien w\u00f6rtlich am selben Tag, aber mehr als 4 Stunden zuvor, auf der russischen Ressource <a href=\"https:\/\/vrubcovske.ru\/news\/ekonomy\/26406-uvolennye-iz-armii-ssha-narkomany-vojujut-sejchas-na-storone-ukrainy.html\">VRUBCOVSKE.RU<\/a> mit einem Link zur Website \u201cRusskaja Wesna\u201d (\u201eRussischer Fr\u00fchling\u201c), die sich wiederum auf die Ausgabe von The American Conservative in den USA bezieht. Nach seiner Ver\u00f6ffentlichung wurde das Material von einer Reihe anderer russischer Medien <a href=\"https:\/\/syfeed.com\/ru\/news-details\/uvolennye-iz-armii-ssha-narkozavisimye-voyuyut-seychas-na-storone-ukrainy-american-conservative_78034137.html\">aufgegriffen<\/a> und <a href=\"http:\/\/mirtesen.ru\/pad\/43343368088\">verbreitet<\/a>.<\/p>\n\n\n\n<p>Es ist nicht das erste Mal, dass dieses amerikanische Magazin als Sprachrohr der Kreml-Propaganda fungiert. Nach Angaben des Zentrums zur Bek\u00e4mpfung von <a href=\"https:\/\/armyinform.com.ua\/2022\/12\/25\/czpd-myrni-peregovory-z-rosiyeyu\/\">Desinformation beim Nationalen Sicherheitsrat der Ukraine<\/a> ver\u00f6ffentlichte The American Conservative zuvor eine Erkl\u00e4rung des pensionierten Oberst der US-Armee, Douglas McGregor, dass die einzige L\u00f6sung f\u00fcr den Ukraine-Konflikt \u201eFriedensverhandlungen und die Anerkennung der legitimen Sicherheitsinteressen Russlands in der Ukraine\u201c seien. <\/p>\n\n\n\n<p>Au\u00dferdem ver\u00f6ffentlichte The American Conservative <a href=\"https:\/\/glavcom.ua\/country\/incidents\/rosija-rozhanjaje-fejki-pro-marnu-dopomohu-ukrajini-vid-ssha-867955.html\">Material <\/a>des Experten D. Bendow, der f\u00fcr seine rhetorische Propaganda der Russischen F\u00f6deration bekannt ist, in dem er betont, dass die Forderungen des Pr\u00e4sidenten der Ukraine Wolodymy Selenskyj, Russland als staatlichen Sponsor des Terrorismus anzuerkennen, \u201enur\u201c seien verkomplizieren die Verhandlungen mit dem Kreml und versuchen zu beweisen, dass die Unterst\u00fctzung der Ukraine durch die Vereinigten Staaten von Amerika \u201enutzlos\u201c sei. So versuchte die russische Propaganda durch ausl\u00e4ndische Sprecher, ein pro-russisches Narrativ \u00fcber die Notwendigkeit von Friedensverhandlungen mit Russland zu den Bedingungen des Aggressorlandes zu verbreiten.<\/p>\n\n\n\n<p>Tats\u00e4chlich dienen B\u00fcrger aus mehr als 50 verschiedenen L\u00e4ndern, darunter auch den Vereinigten Staaten, in der Internationalen Legion der Streitkr\u00e4fte, die der Ukraine im Kampf gegen die russische Aggression helfen.<\/p>\n\n\n\n<p>Am 29. Mai feierten die Vereinigten Staaten den j\u00e4hrlichen Gedenktag f\u00fcr amerikanische Soldaten, die in allen Kriegen und bewaffneten Konflikten, an denen die Vereinigten Staaten jemals teilgenommen haben, ihr Leben lie\u00dfen. Unter ihnen ehrten sie das Andenken amerikanischer Freiwilliger, die ihr Leben lie\u00dfen, um die Ukraine vor dem russischen Angriff zu verteidigen, wie die Washington Post berichtete.<\/p>\n\n\n\n<p>Nach 15 Monaten ausgewachsenem Krieg sind bekannterma\u00dfen mindestens 16 US-Freiwillige bei der Verteidigung der Ukraine gestorben. Es handelte sich um M\u00e4nner unterschiedlichen Alters \u2013 von 26 bis 50 Jahren. Die meisten von ihnen haben lange Zeit in der US-Armee gedient und im Irak, in Afghanistan, in Syrien und im Jemen gek\u00e4mpft.<\/p>\n\n\n\n<p>Die Mutter des J\u00fcngsten von ihnen, den 26-j\u00e4hrigem Cooper T. Andrews, einen pensionierteren Marine-Sergeanten, der im April bei der Evakuierung von Zivilisten in Bachmut starb, sagt, ihr afroamerikanischer Sohn, der mehrere Monate in der Ukraine verbrachte, habe sich genauso gef\u00fchlt wie er in einer ukrainischen Einheit noch komfortabler als in den USA. Er erz\u00e4hlte ihr von seinen Waffenbr\u00fcder: \u201eWir sind wie Br\u00fcder, Mutter\u201c und hatte keinerlei Erscheinungsformen von Rassismus erlebt, die von russischen Propagandisten so oft f\u00e4lschlicherweise betont werden.<\/p>\n\n\n\n<p>Angeh\u00f6rige amerikanischer Soldaten, die in der Ukraine gefallen sind, weisen darauf hin, dass ihr Wunsch, Sicherheit im eigenen Land gegen Hilfe f\u00fcr ein fremdes Land einzutauschen, von denselben demokratischen Idealen inspiriert war, die dem Dienst in den US-Streitkr\u00e4ften zugrunde liegen \u2013 Freiheitsliebe und Verachtung der Tyrannei.<\/p>\n\n\n\n<p>Nach ukrainischem Recht wurden alle ausl\u00e4ndischen Staatsb\u00fcrger und Staatenlosen, die an Feindseligkeiten auf ukrainischer Seite beteiligt waren, auf freiwilliger Basis im Rahmen eines Vertrags zum Milit\u00e4rdienst aufgenommen und sind Kombattanten. Aber die <a href=\"https:\/\/www.unian.ua\/war\/inozemni-viyskovi-v-ukrajini-nazvano-chislo-zagiblih-dobrovolciv-z-ssha-novini-vtorgnennya-rosiji-v-ukrajinu-amp-12274248.html?fbclid=IwAR0bPgu8jvL1SOs-x8ec5lVGI7sPr368bqdq6PHHAj2rSHgOuCf_MV5oc10\">russische Propaganda <\/a>stellt sie als \u201eS\u00f6ldner\u201c dar und organisiert Schauprozesse gegen sie f\u00fcr den Fall, dass sie gefangen genommen werden.<\/p>\n\n\n\n<p>Es sollte betont werden, dass das Portal Niezale\u017cny Dziennik Polityczny bereits am 10. Februar eine sehr \u00e4hnliche Desinformation ver\u00f6ffentlicht hat, die darauf abzielt, das Image des amerikanischen Milit\u00e4rs zu sch\u00e4digen und die Unterst\u00fctzung, die es den L\u00e4ndern an der Ostflanke der NATO, insbesondere Polen, gew\u00e4hrt, abzuwerten, 2022, w\u00e4hrend der <a href=\"https:\/\/dziennik-polityczny.com\/2022\/02\/10\/wojsko-usa-w-polsce-do-mordercow-z-fort-hood-dolaczyli-sie-narkomani-z-fort-bragg\/\">Konzentration russischer Truppen<\/a> nahe der Grenze zur Ukraine am Tag vor einer gro\u00df angelegten Invasion. Diese gef\u00e4lschten Nachrichten wurden dann vom <a href=\"https:\/\/fakehunter.pap.pl\/raport\/3986885e-d977-413d-bd02-9b5e5f06bdf7?fbclid=IwAR3Aa8Q9AWyOVsQQqYSLfknH4PIbOoIZkshMaZInFN0OM_-5JGwK4d9YTKk\">Experten Tadeusz Wrubel<\/a> von Polski Zbrojna, der monatlichen Ver\u00f6ffentlichung des Milit\u00e4rverlagsinstituts des polnischen Verteidigungsministeriums, untersucht und widerlegt.<\/p>\n\n\n\n<p>Wie man sehen kann, nutzen Kreml-Provokateure die Methode des Propagandachefs des Dritten Reiches, J. Goebbels, die darin besteht, Informationen durch st\u00e4ndige Wiederholung aufzuzwingen und funktioniert nach dem Prinzip \u201eEine tausendmal wiederholte L\u00fcge wird zur Wahrheit.\u201c<\/p>\n\n\n\n<p><strong>Anatolii Kurnosow<\/strong><\/p>\n\n\n\n<p><em>Das Material wurde im Rahmen des Projekts \u201eStop Lie\u201c des \u201eWohlt\u00e4tigen Fonds der Polnisch-Ukrainischen Partnerschaft\u201c im Rahmen des Projekts \u201eUrgent EU Support for Civil Society\u201c erstellt, das vom ISAR Ednannia mit der finanziellen Unterst\u00fctzung der Europ\u00e4ischen Union umgesetzt wird. <\/em>Der Inhalt liegt in der alleinigen Verantwortung vom Autor und spiegelt nicht unbedingt die Position der Europ\u00e4ischen Union wider.<\/p>\n\n\n\n<p><a href=\"https:\/\/www.facebook.com\/hashtag\/%D0%BF%D1%80%D1%8F%D0%BC%D1%83%D1%94%D0%BC%D0%BE%D1%80%D0%B0%D0%B7%D0%BE%D0%BC?__eep__=6&amp;__cft__[0]=AZUWgygLHtxoLmIIQt0vg2V9v-x2oX-ENlqUwUGLMoFUB7A6ozyYl5Uxumh-D8GXEyTVQfZyH19_SWW6Bgy-hbcU5OdtMwZV0IO7DRfBrxIs6N9yt7hQGF7W0dT_sck7Ca57ARIcGs2dqq4OftJwpEl-fqkVi3S9m4KIyCI7U2aCRS07Jx3k-8kxhYP1dJV719A&amp;__tn__=*NK-R\" target=\"_blank\" rel=\"noreferrer noopener\">#\u041f\u0440\u044f\u043c\u0443\u0454\u043c\u043e\u0420\u0430\u0437\u043e\u043c<\/a> <a href=\"https:\/\/www.facebook.com\/hashtag\/teameurope?__eep__=6&amp;__cft__[0]=AZUWgygLHtxoLmIIQt0vg2V9v-x2oX-ENlqUwUGLMoFUB7A6ozyYl5Uxumh-D8GXEyTVQfZyH19_SWW6Bgy-hbcU5OdtMwZV0IO7DRfBrxIs6N9yt7hQGF7W0dT_sck7Ca57ARIcGs2dqq4OftJwpEl-fqkVi3S9m4KIyCI7U2aCRS07Jx3k-8kxhYP1dJV719A&amp;__tn__=*NK-R\" target=\"_blank\" rel=\"noreferrer noopener\">#TeamEurope<\/a> <a href=\"https:\/\/www.facebook.com\/hashtag\/movingforwardtogether?__eep__=6&amp;__cft__[0]=AZUWgygLHtxoLmIIQt0vg2V9v-x2oX-ENlqUwUGLMoFUB7A6ozyYl5Uxumh-D8GXEyTVQfZyH19_SWW6Bgy-hbcU5OdtMwZV0IO7DRfBrxIs6N9yt7hQGF7W0dT_sck7Ca57ARIcGs2dqq4OftJwpEl-fqkVi3S9m4KIyCI7U2aCRS07Jx3k-8kxhYP1dJV719A&amp;__tn__=*NK-R\" target=\"_blank\" rel=\"noreferrer noopener\">#MovingForwardTogether<\/a> <a href=\"https:\/\/www.facebook.com\/hashtag\/isarednannia?__eep__=6&amp;__cft__[0]=AZUWgygLHtxoLmIIQt0vg2V9v-x2oX-ENlqUwUGLMoFUB7A6ozyYl5Uxumh-D8GXEyTVQfZyH19_SWW6Bgy-hbcU5OdtMwZV0IO7DRfBrxIs6N9yt7hQGF7W0dT_sck7Ca57ARIcGs2dqq4OftJwpEl-fqkVi3S9m4KIyCI7U2aCRS07Jx3k-8kxhYP1dJV719A&amp;__tn__=*NK-R\" target=\"_blank\" rel=\"noreferrer noopener\">#ISAREdnannia<\/a> <a href=\"https:\/\/www.facebook.com\/hashtag\/stoplie?__eep__=6&amp;__cft__[0]=AZUWgygLHtxoLmIIQt0vg2V9v-x2oX-ENlqUwUGLMoFUB7A6ozyYl5Uxumh-D8GXEyTVQfZyH19_SWW6Bgy-hbcU5OdtMwZV0IO7DRfBrxIs6N9yt7hQGF7W0dT_sck7Ca57ARIcGs2dqq4OftJwpEl-fqkVi3S9m4KIyCI7U2aCRS07Jx3k-8kxhYP1dJV719A&amp;__tn__=*NK-R\" target=\"_blank\" rel=\"noreferrer noopener\">#StopLie<\/a><\/p>\n\n\n\n<p><a href=\"https:\/\/www.facebook.com\/isar.ednannia?__cft__[0]=AZUWgygLHtxoLmIIQt0vg2V9v-x2oX-ENlqUwUGLMoFUB7A6ozyYl5Uxumh-D8GXEyTVQfZyH19_SWW6Bgy-hbcU5OdtMwZV0IO7DRfBrxIs6N9yt7hQGF7W0dT_sck7Ca57ARIcGs2dqq4OftJwpEl-fqkVi3S9m4KIyCI7U2aCRS07Jx3k-8kxhYP1dJV719A&amp;__tn__=-]K-R\" target=\"_blank\" rel=\"noreferrer noopener\">Isar Ednannia<\/a><a href=\"https:\/\/www.facebook.com\/EUDelegationUkraine?__cft__[0]=AZUWgygLHtxoLmIIQt0vg2V9v-x2oX-ENlqUwUGLMoFUB7A6ozyYl5Uxumh-D8GXEyTVQfZyH19_SWW6Bgy-hbcU5OdtMwZV0IO7DRfBrxIs6N9yt7hQGF7W0dT_sck7Ca57ARIcGs2dqq4OftJwpEl-fqkVi3S9m4KIyCI7U2aCRS07Jx3k-8kxhYP1dJV719A&amp;__tn__=-]K-R\" target=\"_blank\" rel=\"noreferrer noopener\"> European Union in Ukraine<\/a><a href=\"https:\/\/www.facebook.com\/bf.pol.ukr.partnerstwa?__cft__[0]=AZUWgygLHtxoLmIIQt0vg2V9v-x2oX-ENlqUwUGLMoFUB7A6ozyYl5Uxumh-D8GXEyTVQfZyH19_SWW6Bgy-hbcU5OdtMwZV0IO7DRfBrxIs6N9yt7hQGF7W0dT_sck7Ca57ARIcGs2dqq4OftJwpEl-fqkVi3S9m4KIyCI7U2aCRS07Jx3k-8kxhYP1dJV719A&amp;__tn__=-]K-R\" target=\"_blank\" rel=\"noreferrer noopener\"> \u0411\u043b\u0430\u0433\u043e\u0434\u0456\u0439\u043d\u0438\u0439 \u0444\u043e\u043d\u0434 \u043f\u043e\u043b\u044c\u0441\u044c\u043a\u043e-\u0443\u043a\u0440\u0430\u0457\u043d\u0441\u044c\u043a\u043e\u0433\u043e \u043f\u0430\u0440\u0442\u043d\u0435\u0440\u0441\u0442\u0432\u0430<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Der polnischsprachige Telegram-Kanal der Internetpublikation Niezale\u017cny Dziennik Polityczny, bekannt f\u00fcr die st\u00e4ndige Verbreitung von Fakes und russischen Propagandainhalten, ver\u00f6ffentlichte einen Artikel mit dem Titel \u201eDrogenabh\u00e4ngige aus der Armee entlassene US-Soldaten k\u00e4mpfen jetzt auf der Seite der Ukraine\u201c (\u00abUzale\u017cnieni od narkotyk\u00f3w \u017co\u0142nierze US Army zwolnieni z wojska walcz\u0105 teraz po stronie Ukrainy\u00bb). Der Text nutzt die [&hellip;]<\/p>\n","protected":false},"author":27,"featured_media":124085,"comment_status":"closed","ping_status":"open","sticky":true,"template":"","format":"standard","meta":{"_exactmetrics_skip_tracking":false,"_exactmetrics_sitenote_active":false,"_exactmetrics_sitenote_note":"","_exactmetrics_sitenote_category":0,"footnotes":""},"categories":[20641,20640,2195,20498],"tags":[],"class_list":["post-124084","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-stop-lie-spezialprojekt","category-in-polen","category-ua-in-polish","category-ua-spsl"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Fake: Drogenabh\u00e4ngige Soldaten der US-Armee, die aus der Armee entlassen wurden, k\u00e4mpfen nun auf der Seite der Ukraine &#8211; U.P.M.P<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/upmp.news\/de\/stop-lie-spezialprojekt\/strong-fake-drogenabhangige-soldaten-der-us-armee-die-aus-der-armee-entlassen-wurden-kampfen-nun-auf-der-seite-der-ukraine-strong\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Fake: Drogenabh\u00e4ngige Soldaten der US-Armee, die aus der Armee entlassen wurden, k\u00e4mpfen nun auf der Seite der Ukraine &#8211; U.P.M.P\" \/>\n<meta property=\"og:description\" content=\"Der polnischsprachige Telegram-Kanal der Internetpublikation Niezale\u017cny Dziennik Polityczny, bekannt f\u00fcr die st\u00e4ndige Verbreitung von Fakes und russischen Propagandainhalten, ver\u00f6ffentlichte einen Artikel mit dem Titel \u201eDrogenabh\u00e4ngige aus der Armee entlassene US-Soldaten k\u00e4mpfen jetzt auf der Seite der Ukraine\u201c (\u00abUzale\u017cnieni od narkotyk\u00f3w \u017co\u0142nierze US Army zwolnieni z wojska walcz\u0105 teraz po stronie Ukrainy\u00bb). Der Text nutzt die [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/upmp.news\/de\/stop-lie-spezialprojekt\/strong-fake-drogenabhangige-soldaten-der-us-armee-die-aus-der-armee-entlassen-wurden-kampfen-nun-auf-der-seite-der-ukraine-strong\/\" \/>\n<meta property=\"og:site_name\" content=\"U.P.M.P\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/upmp.news\/\" \/>\n<meta property=\"article:published_time\" content=\"2023-06-24T07:43:45+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-07-04T11:14:07+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/upmp.news\/wp-content\/uploads\/2023\/06\/3St1-IMG-20230619-WA0003-2.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1600\" \/>\n\t<meta property=\"og:image:height\" content=\"753\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"vladimyr\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@maininua\" \/>\n<meta name=\"twitter:site\" content=\"@maininua\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"vladimyr\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"5\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/upmp.news\\\/de\\\/stop-lie-spezialprojekt\\\/strong-fake-drogenabhangige-soldaten-der-us-armee-die-aus-der-armee-entlassen-wurden-kampfen-nun-auf-der-seite-der-ukraine-strong\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/upmp.news\\\/de\\\/stop-lie-spezialprojekt\\\/strong-fake-drogenabhangige-soldaten-der-us-armee-die-aus-der-armee-entlassen-wurden-kampfen-nun-auf-der-seite-der-ukraine-strong\\\/\"},\"author\":{\"name\":\"vladimyr\",\"@id\":\"https:\\\/\\\/upmp.news\\\/#\\\/schema\\\/person\\\/cebd3113030eb01f184505010f519d71\"},\"headline\":\"Fake: Drogenabh\u00e4ngige Soldaten der US-Armee, die aus der Armee entlassen wurden, k\u00e4mpfen nun auf der Seite der Ukraine\",\"datePublished\":\"2023-06-24T07:43:45+00:00\",\"dateModified\":\"2023-07-04T11:14:07+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/upmp.news\\\/de\\\/stop-lie-spezialprojekt\\\/strong-fake-drogenabhangige-soldaten-der-us-armee-die-aus-der-armee-entlassen-wurden-kampfen-nun-auf-der-seite-der-ukraine-strong\\\/\"},\"wordCount\":970,\"image\":{\"@id\":\"https:\\\/\\\/upmp.news\\\/de\\\/stop-lie-spezialprojekt\\\/strong-fake-drogenabhangige-soldaten-der-us-armee-die-aus-der-armee-entlassen-wurden-kampfen-nun-auf-der-seite-der-ukraine-strong\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/upmp.news\\\/wp-content\\\/uploads\\\/2023\\\/06\\\/3St1-IMG-20230619-WA0003-2.jpg\",\"articleSection\":[\"\\\"Stop Lie\\\"-Spezialprojekt\",\"In Polen\",\"\u0412 \u041f\u043e\u043b\u044c\u0449\u0456\",\"\u0421\u043f\u0435\u0446\u043f\u0440\u043e\u0454\u043a\u0442 \\\"Stop Lie\\\"\"],\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/upmp.news\\\/de\\\/stop-lie-spezialprojekt\\\/strong-fake-drogenabhangige-soldaten-der-us-armee-die-aus-der-armee-entlassen-wurden-kampfen-nun-auf-der-seite-der-ukraine-strong\\\/\",\"url\":\"https:\\\/\\\/upmp.news\\\/de\\\/stop-lie-spezialprojekt\\\/strong-fake-drogenabhangige-soldaten-der-us-armee-die-aus-der-armee-entlassen-wurden-kampfen-nun-auf-der-seite-der-ukraine-strong\\\/\",\"name\":\"Fake: Drogenabh\u00e4ngige Soldaten der US-Armee, die aus der Armee entlassen wurden, k\u00e4mpfen nun auf der Seite der Ukraine &#8211; U.P.M.P\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/upmp.news\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/upmp.news\\\/de\\\/stop-lie-spezialprojekt\\\/strong-fake-drogenabhangige-soldaten-der-us-armee-die-aus-der-armee-entlassen-wurden-kampfen-nun-auf-der-seite-der-ukraine-strong\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/upmp.news\\\/de\\\/stop-lie-spezialprojekt\\\/strong-fake-drogenabhangige-soldaten-der-us-armee-die-aus-der-armee-entlassen-wurden-kampfen-nun-auf-der-seite-der-ukraine-strong\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/upmp.news\\\/wp-content\\\/uploads\\\/2023\\\/06\\\/3St1-IMG-20230619-WA0003-2.jpg\",\"datePublished\":\"2023-06-24T07:43:45+00:00\",\"dateModified\":\"2023-07-04T11:14:07+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/upmp.news\\\/#\\\/schema\\\/person\\\/cebd3113030eb01f184505010f519d71\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/upmp.news\\\/de\\\/stop-lie-spezialprojekt\\\/strong-fake-drogenabhangige-soldaten-der-us-armee-die-aus-der-armee-entlassen-wurden-kampfen-nun-auf-der-seite-der-ukraine-strong\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/upmp.news\\\/de\\\/stop-lie-spezialprojekt\\\/strong-fake-drogenabhangige-soldaten-der-us-armee-die-aus-der-armee-entlassen-wurden-kampfen-nun-auf-der-seite-der-ukraine-strong\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/upmp.news\\\/de\\\/stop-lie-spezialprojekt\\\/strong-fake-drogenabhangige-soldaten-der-us-armee-die-aus-der-armee-entlassen-wurden-kampfen-nun-auf-der-seite-der-ukraine-strong\\\/#primaryimage\",\"url\":\"https:\\\/\\\/upmp.news\\\/wp-content\\\/uploads\\\/2023\\\/06\\\/3St1-IMG-20230619-WA0003-2.jpg\",\"contentUrl\":\"https:\\\/\\\/upmp.news\\\/wp-content\\\/uploads\\\/2023\\\/06\\\/3St1-IMG-20230619-WA0003-2.jpg\",\"width\":1600,\"height\":753,\"caption\":\"Illustration von Inna Krystal\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/upmp.news\\\/de\\\/stop-lie-spezialprojekt\\\/strong-fake-drogenabhangige-soldaten-der-us-armee-die-aus-der-armee-entlassen-wurden-kampfen-nun-auf-der-seite-der-ukraine-strong\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/upmp.news\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Fake: Drogenabh\u00e4ngige Soldaten der US-Armee, die aus der Armee entlassen wurden, k\u00e4mpfen nun auf der Seite der Ukraine\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/upmp.news\\\/#website\",\"url\":\"https:\\\/\\\/upmp.news\\\/\",\"name\":\"U.P.M.P\",\"description\":\"\u0423\u043a\u0440\u0430\u0457\u043d\u043e-\u043f\u043e\u043b\u044c\u0441\u044c\u043a\u0430 \u043c\u0435\u0434\u0456\u0430\u043f\u043b\u0430\u0442\u0444\u043e\u0440\u043c\u0430\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/upmp.news\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/upmp.news\\\/#\\\/schema\\\/person\\\/cebd3113030eb01f184505010f519d71\",\"name\":\"vladimyr\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/upmp.news\\\/wp-content\\\/uploads\\\/2017\\\/12\\\/ava.png\",\"url\":\"https:\\\/\\\/upmp.news\\\/wp-content\\\/uploads\\\/2017\\\/12\\\/ava.png\",\"contentUrl\":\"https:\\\/\\\/upmp.news\\\/wp-content\\\/uploads\\\/2017\\\/12\\\/ava.png\",\"caption\":\"vladimyr\"},\"url\":\"https:\\\/\\\/upmp.news\\\/de\\\/author\\\/vladimyr\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Fake: Drogenabh\u00e4ngige Soldaten der US-Armee, die aus der Armee entlassen wurden, k\u00e4mpfen nun auf der Seite der Ukraine &#8211; U.P.M.P","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/upmp.news\/de\/stop-lie-spezialprojekt\/strong-fake-drogenabhangige-soldaten-der-us-armee-die-aus-der-armee-entlassen-wurden-kampfen-nun-auf-der-seite-der-ukraine-strong\/","og_locale":"de_DE","og_type":"article","og_title":"Fake: Drogenabh\u00e4ngige Soldaten der US-Armee, die aus der Armee entlassen wurden, k\u00e4mpfen nun auf der Seite der Ukraine &#8211; U.P.M.P","og_description":"Der polnischsprachige Telegram-Kanal der Internetpublikation Niezale\u017cny Dziennik Polityczny, bekannt f\u00fcr die st\u00e4ndige Verbreitung von Fakes und russischen Propagandainhalten, ver\u00f6ffentlichte einen Artikel mit dem Titel \u201eDrogenabh\u00e4ngige aus der Armee entlassene US-Soldaten k\u00e4mpfen jetzt auf der Seite der Ukraine\u201c (\u00abUzale\u017cnieni od narkotyk\u00f3w \u017co\u0142nierze US Army zwolnieni z wojska walcz\u0105 teraz po stronie Ukrainy\u00bb). Der Text nutzt die [&hellip;]","og_url":"https:\/\/upmp.news\/de\/stop-lie-spezialprojekt\/strong-fake-drogenabhangige-soldaten-der-us-armee-die-aus-der-armee-entlassen-wurden-kampfen-nun-auf-der-seite-der-ukraine-strong\/","og_site_name":"U.P.M.P","article_publisher":"https:\/\/www.facebook.com\/upmp.news\/","article_published_time":"2023-06-24T07:43:45+00:00","article_modified_time":"2023-07-04T11:14:07+00:00","og_image":[{"width":1600,"height":753,"url":"https:\/\/upmp.news\/wp-content\/uploads\/2023\/06\/3St1-IMG-20230619-WA0003-2.jpg","type":"image\/jpeg"}],"author":"vladimyr","twitter_card":"summary_large_image","twitter_creator":"@maininua","twitter_site":"@maininua","twitter_misc":{"Verfasst von":"vladimyr","Gesch\u00e4tzte Lesezeit":"5\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/upmp.news\/de\/stop-lie-spezialprojekt\/strong-fake-drogenabhangige-soldaten-der-us-armee-die-aus-der-armee-entlassen-wurden-kampfen-nun-auf-der-seite-der-ukraine-strong\/#article","isPartOf":{"@id":"https:\/\/upmp.news\/de\/stop-lie-spezialprojekt\/strong-fake-drogenabhangige-soldaten-der-us-armee-die-aus-der-armee-entlassen-wurden-kampfen-nun-auf-der-seite-der-ukraine-strong\/"},"author":{"name":"vladimyr","@id":"https:\/\/upmp.news\/#\/schema\/person\/cebd3113030eb01f184505010f519d71"},"headline":"Fake: Drogenabh\u00e4ngige Soldaten der US-Armee, die aus der Armee entlassen wurden, k\u00e4mpfen nun auf der Seite der Ukraine","datePublished":"2023-06-24T07:43:45+00:00","dateModified":"2023-07-04T11:14:07+00:00","mainEntityOfPage":{"@id":"https:\/\/upmp.news\/de\/stop-lie-spezialprojekt\/strong-fake-drogenabhangige-soldaten-der-us-armee-die-aus-der-armee-entlassen-wurden-kampfen-nun-auf-der-seite-der-ukraine-strong\/"},"wordCount":970,"image":{"@id":"https:\/\/upmp.news\/de\/stop-lie-spezialprojekt\/strong-fake-drogenabhangige-soldaten-der-us-armee-die-aus-der-armee-entlassen-wurden-kampfen-nun-auf-der-seite-der-ukraine-strong\/#primaryimage"},"thumbnailUrl":"https:\/\/upmp.news\/wp-content\/uploads\/2023\/06\/3St1-IMG-20230619-WA0003-2.jpg","articleSection":["\"Stop Lie\"-Spezialprojekt","In Polen","\u0412 \u041f\u043e\u043b\u044c\u0449\u0456","\u0421\u043f\u0435\u0446\u043f\u0440\u043e\u0454\u043a\u0442 \"Stop Lie\""],"inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/upmp.news\/de\/stop-lie-spezialprojekt\/strong-fake-drogenabhangige-soldaten-der-us-armee-die-aus-der-armee-entlassen-wurden-kampfen-nun-auf-der-seite-der-ukraine-strong\/","url":"https:\/\/upmp.news\/de\/stop-lie-spezialprojekt\/strong-fake-drogenabhangige-soldaten-der-us-armee-die-aus-der-armee-entlassen-wurden-kampfen-nun-auf-der-seite-der-ukraine-strong\/","name":"Fake: Drogenabh\u00e4ngige Soldaten der US-Armee, die aus der Armee entlassen wurden, k\u00e4mpfen nun auf der Seite der Ukraine &#8211; U.P.M.P","isPartOf":{"@id":"https:\/\/upmp.news\/#website"},"primaryImageOfPage":{"@id":"https:\/\/upmp.news\/de\/stop-lie-spezialprojekt\/strong-fake-drogenabhangige-soldaten-der-us-armee-die-aus-der-armee-entlassen-wurden-kampfen-nun-auf-der-seite-der-ukraine-strong\/#primaryimage"},"image":{"@id":"https:\/\/upmp.news\/de\/stop-lie-spezialprojekt\/strong-fake-drogenabhangige-soldaten-der-us-armee-die-aus-der-armee-entlassen-wurden-kampfen-nun-auf-der-seite-der-ukraine-strong\/#primaryimage"},"thumbnailUrl":"https:\/\/upmp.news\/wp-content\/uploads\/2023\/06\/3St1-IMG-20230619-WA0003-2.jpg","datePublished":"2023-06-24T07:43:45+00:00","dateModified":"2023-07-04T11:14:07+00:00","author":{"@id":"https:\/\/upmp.news\/#\/schema\/person\/cebd3113030eb01f184505010f519d71"},"breadcrumb":{"@id":"https:\/\/upmp.news\/de\/stop-lie-spezialprojekt\/strong-fake-drogenabhangige-soldaten-der-us-armee-die-aus-der-armee-entlassen-wurden-kampfen-nun-auf-der-seite-der-ukraine-strong\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/upmp.news\/de\/stop-lie-spezialprojekt\/strong-fake-drogenabhangige-soldaten-der-us-armee-die-aus-der-armee-entlassen-wurden-kampfen-nun-auf-der-seite-der-ukraine-strong\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/upmp.news\/de\/stop-lie-spezialprojekt\/strong-fake-drogenabhangige-soldaten-der-us-armee-die-aus-der-armee-entlassen-wurden-kampfen-nun-auf-der-seite-der-ukraine-strong\/#primaryimage","url":"https:\/\/upmp.news\/wp-content\/uploads\/2023\/06\/3St1-IMG-20230619-WA0003-2.jpg","contentUrl":"https:\/\/upmp.news\/wp-content\/uploads\/2023\/06\/3St1-IMG-20230619-WA0003-2.jpg","width":1600,"height":753,"caption":"Illustration von Inna Krystal"},{"@type":"BreadcrumbList","@id":"https:\/\/upmp.news\/de\/stop-lie-spezialprojekt\/strong-fake-drogenabhangige-soldaten-der-us-armee-die-aus-der-armee-entlassen-wurden-kampfen-nun-auf-der-seite-der-ukraine-strong\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/upmp.news\/"},{"@type":"ListItem","position":2,"name":"Fake: Drogenabh\u00e4ngige Soldaten der US-Armee, die aus der Armee entlassen wurden, k\u00e4mpfen nun auf der Seite der Ukraine"}]},{"@type":"WebSite","@id":"https:\/\/upmp.news\/#website","url":"https:\/\/upmp.news\/","name":"U.P.M.P","description":"\u0423\u043a\u0440\u0430\u0457\u043d\u043e-\u043f\u043e\u043b\u044c\u0441\u044c\u043a\u0430 \u043c\u0435\u0434\u0456\u0430\u043f\u043b\u0430\u0442\u0444\u043e\u0440\u043c\u0430","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/upmp.news\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Person","@id":"https:\/\/upmp.news\/#\/schema\/person\/cebd3113030eb01f184505010f519d71","name":"vladimyr","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/upmp.news\/wp-content\/uploads\/2017\/12\/ava.png","url":"https:\/\/upmp.news\/wp-content\/uploads\/2017\/12\/ava.png","contentUrl":"https:\/\/upmp.news\/wp-content\/uploads\/2017\/12\/ava.png","caption":"vladimyr"},"url":"https:\/\/upmp.news\/de\/author\/vladimyr\/"}]}},"_links":{"self":[{"href":"https:\/\/upmp.news\/de\/wp-json\/wp\/v2\/posts\/124084","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/upmp.news\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/upmp.news\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/upmp.news\/de\/wp-json\/wp\/v2\/users\/27"}],"replies":[{"embeddable":true,"href":"https:\/\/upmp.news\/de\/wp-json\/wp\/v2\/comments?post=124084"}],"version-history":[{"count":3,"href":"https:\/\/upmp.news\/de\/wp-json\/wp\/v2\/posts\/124084\/revisions"}],"predecessor-version":[{"id":254618,"href":"https:\/\/upmp.news\/de\/wp-json\/wp\/v2\/posts\/124084\/revisions\/254618"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/upmp.news\/de\/wp-json\/wp\/v2\/media\/124085"}],"wp:attachment":[{"href":"https:\/\/upmp.news\/de\/wp-json\/wp\/v2\/media?parent=124084"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/upmp.news\/de\/wp-json\/wp\/v2\/categories?post=124084"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/upmp.news\/de\/wp-json\/wp\/v2\/tags?post=124084"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}