{"id":268369,"date":"2024-02-09T13:02:55","date_gmt":"2024-02-09T11:02:55","guid":{"rendered":"https:\/\/upmp.news\/?p=268369"},"modified":"2024-02-09T13:02:56","modified_gmt":"2024-02-09T11:02:56","slug":"verteidigungsminister-nennt-prioritaeten-fuer-die-armee","status":"publish","type":"post","link":"https:\/\/upmp.news\/de\/in-polen\/verteidigungsminister-nennt-prioritaeten-fuer-die-armee\/","title":{"rendered":"Verteidigungsminister nennt Priorit\u00e4ten f\u00fcr die Armee"},"content":{"rendered":"\n<p><strong>Zu den wichtigsten Zielen des Ministeriums geh\u00f6re der Aufbau einer starken nationalen Gemeinschaft, die in der Lage sei, das Land zu verteidigen und in voller Alarmbereitschaft zu bleiben. Dazu habe die Regierung den h\u00f6chsten Armeehaushalt seit Jahren verabschiedet und eine Erh\u00f6hung der Geh\u00e4lter f\u00fcr Soldaten eingef\u00fchrt, teilte Polens stellvertretender Premierminister mit.<\/strong> <strong>Dies wird von Upmp.news unter <a href=\"https:\/\/www.polskieradio.pl\/400\/7764\/Artykul\/3332322,verteidigungsminister-nennt-priorit%C3%A4ten-f%C3%BCr-die-armee\">Bezugnahme<\/a> auf \u201ePolskie Radio\u201c gemeldet.<\/strong><\/p>\n\n\n\n<p>Parlamentarier debattierten am Donnerstagabend mehr als f\u00fcnf Stunden zu aktuellen Verteidigungsproblemen und Pl\u00e4nen des Ministeriums. Der stellvertretende Premierminister, W\u0142adys\u0142aw Kosiniak-Kamysz, informierte \u00fcber die Hauptpriorit\u00e4ten des Verteidigungsministeriums, darunter R\u00fcstungspl\u00e4ne und die Aktualisierung der nationalen Sicherheitsstrategie. Zu den wichtigsten Zielen des Ministeriums geh\u00f6re der Aufbau einer starken nationalen Gemeinschaft, die in der Lage sei, das Land zu verteidigen und in voller Alarmbereitschaft zu bleiben, sagte der Minister nach dem Treffen vor Reportern. Er betonte auch B\u00fcndnisse innerhalb der Europ\u00e4ischen Union und der NATO sowie den Aufbau einer starken, gut gef\u00fchrten und modernisierten Armee.<\/p>\n\n\n\n<p>W\u00e4hrend der Sitzung warfen sich die Abgeordneten der Opposition und der Regierungskoalition gegenseitig Fehler bei der Modernisierung und den geplanten Ver\u00e4nderungen in der Armee vor. Nach Beendigung des Ausschusses erkl\u00e4rten jedoch sowohl der Verteidigungsminister als auch Abgeordnete der oppositionellen Recht und Gerechtigkeit (PiS), dass das Thema Verteidigung die politische Klasse vereinen m\u00fcsse. Micha\u0142 Dworczyk von der PiS lobte die Entscheidung des Verteidigungsministeriums, sinnvolle R\u00fcstungsprogramme der Vorg\u00e4ngerregierung fortzusetzen.<\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-rich is-provider-twitter wp-block-embed-twitter\"><div class=\"wp-block-embed__wrapper\">\n<div class=\"newspaper-x-video-container\"><blockquote class=\"twitter-tweet\" data-width=\"550\" data-dnt=\"true\"><p lang=\"pl\" dir=\"ltr\">Wicepremier, minister obrony narodowej W. <a href=\"https:\/\/twitter.com\/KosiniakKamysz?ref_src=twsrc%5Etfw\">@KosiniakKamysz<\/a> o najwa\u017cniejszych zadaniach MON:<br>&#8211; stworzenie aktualnych dokument\u00f3w strategicznych. Rozpoczynamy nowy cykl strategiczno \u2013 planistyczny uwzgl\u0119dniaj\u0105cy radykalnie zmienione warunki bezpiecze\u0144stwa Polski i wynikaj\u0105ce z tego\u2026 <a href=\"https:\/\/t.co\/ocCXnmtY2c\">pic.twitter.com\/ocCXnmtY2c<\/a><\/p>&mdash; Ministerstwo Obrony Narodowej \ud83c\uddf5\ud83c\uddf1 (@MON_GOV_PL) <a href=\"https:\/\/twitter.com\/MON_GOV_PL\/status\/1755628820760039726?ref_src=twsrc%5Etfw\">February 8, 2024<\/a><\/blockquote><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/div>\n<\/div><\/figure>\n\n\n\n<p>Wie der Vorsitzende des Ausschusses, Andrzej Grzyb von der Polnischen Bauernpartei &#8211; Dritter Weg, erkl\u00e4rte, w\u00fcrden die Abgeordneten trotz der langen Diskussion noch einmal mit dem Minister in einer geschlossenen Sitzung sprechen wollen. Die Abgeordneten h\u00e4tten sich darauf geeinigt, bestimmte Themen nicht \u00f6ffentlich zu behandeln, so der Vorsitzende.<\/p>\n\n\n\n<p>W\u00e4hrend der Sitzung erinnerte der stellvertretende Ministerpr\u00e4sident, dass die Regierung den h\u00f6chsten Armeehaushalt seit Jahren verabschiedet und eine Erh\u00f6hung der Geh\u00e4lter f\u00fcr Soldaten eingef\u00fchrt habe. Die Verteidigungsausgaben seien auf \u00fcber 35 Milliarden EUR gestiegen. Er versprach Dienstalterszuschl\u00e4ge ab dem ersten Dienstjahr einzuf\u00fchren, um die Soldaten zu motivieren, l\u00e4nger im Dienst zu bleiben.<\/p>\n\n\n\n<p>Quelle: IAR\/ps<\/p>\n<div class=\"newspaper-x-tags\"><strong><\/strong><span><a href=\"https:\/\/upmp.news\/de\/tag\/andrzej-grzyb\/\" rel=\"tag\">Andrzej Grzyb<\/a><\/span><a href=\"https:\/\/upmp.news\/de\/tag\/michal-dworczyk\/\" rel=\"tag\">Micha\u0142 Dworczyk<\/a><\/span><a href=\"https:\/\/upmp.news\/de\/tag\/wladyslaw-kosiniak-kamysz-3\/\" rel=\"tag\">W\u0142adys\u0142aw Kosiniak-Kamysz<\/a> <\/div>","protected":false},"excerpt":{"rendered":"<p>Zu den wichtigsten Zielen des Ministeriums geh\u00f6re der Aufbau einer starken nationalen Gemeinschaft, die in der Lage sei, das Land zu verteidigen und in voller Alarmbereitschaft zu bleiben. Dazu habe die Regierung den h\u00f6chsten Armeehaushalt seit Jahren verabschiedet und eine Erh\u00f6hung der Geh\u00e4lter f\u00fcr Soldaten eingef\u00fchrt, teilte Polens stellvertretender Premierminister mit. Dies wird von Upmp.news [&hellip;]<\/p>\n","protected":false},"author":27,"featured_media":268370,"comment_status":"closed","ping_status":"open","sticky":true,"template":"","format":"standard","meta":{"_exactmetrics_skip_tracking":false,"_exactmetrics_sitenote_active":false,"_exactmetrics_sitenote_note":"","_exactmetrics_sitenote_category":0,"footnotes":""},"categories":[20640],"tags":[22425,22426,22401],"class_list":["post-268369","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-in-polen","tag-andrzej-grzyb","tag-michal-dworczyk","tag-wladyslaw-kosiniak-kamysz-3"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Verteidigungsminister nennt Priorit\u00e4ten f\u00fcr die Armee &#8211; U.P.M.P<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/upmp.news\/de\/in-polen\/verteidigungsminister-nennt-prioritaeten-fuer-die-armee\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Verteidigungsminister nennt Priorit\u00e4ten f\u00fcr die Armee &#8211; U.P.M.P\" \/>\n<meta property=\"og:description\" content=\"Zu den wichtigsten Zielen des Ministeriums geh\u00f6re der Aufbau einer starken nationalen Gemeinschaft, die in der Lage sei, das Land zu verteidigen und in voller Alarmbereitschaft zu bleiben. Dazu habe die Regierung den h\u00f6chsten Armeehaushalt seit Jahren verabschiedet und eine Erh\u00f6hung der Geh\u00e4lter f\u00fcr Soldaten eingef\u00fchrt, teilte Polens stellvertretender Premierminister mit. Dies wird von Upmp.news [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/upmp.news\/de\/in-polen\/verteidigungsminister-nennt-prioritaeten-fuer-die-armee\/\" \/>\n<meta property=\"og:site_name\" content=\"U.P.M.P\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/upmp.news\/\" \/>\n<meta property=\"article:published_time\" content=\"2024-02-09T11:02:55+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-02-09T11:02:56+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/upmp.news\/wp-content\/uploads\/2024\/02\/Verteidigungsminister-nennt-Prioritaten-fur-die-Armee.png\" \/>\n\t<meta property=\"og:image:width\" content=\"938\" \/>\n\t<meta property=\"og:image:height\" content=\"515\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"vladimyr\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@maininua\" \/>\n<meta name=\"twitter:site\" content=\"@maininua\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"vladimyr\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"2\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/upmp.news\\\/de\\\/in-polen\\\/verteidigungsminister-nennt-prioritaeten-fuer-die-armee\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/upmp.news\\\/de\\\/in-polen\\\/verteidigungsminister-nennt-prioritaeten-fuer-die-armee\\\/\"},\"author\":{\"name\":\"vladimyr\",\"@id\":\"https:\\\/\\\/upmp.news\\\/#\\\/schema\\\/person\\\/cebd3113030eb01f184505010f519d71\"},\"headline\":\"Verteidigungsminister nennt Priorit\u00e4ten f\u00fcr die Armee\",\"datePublished\":\"2024-02-09T11:02:55+00:00\",\"dateModified\":\"2024-02-09T11:02:56+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/upmp.news\\\/de\\\/in-polen\\\/verteidigungsminister-nennt-prioritaeten-fuer-die-armee\\\/\"},\"wordCount\":373,\"image\":{\"@id\":\"https:\\\/\\\/upmp.news\\\/de\\\/in-polen\\\/verteidigungsminister-nennt-prioritaeten-fuer-die-armee\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/upmp.news\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/Verteidigungsminister-nennt-Prioritaten-fur-die-Armee.png\",\"keywords\":[\"Andrzej Grzyb\",\"Micha\u0142 Dworczyk\",\"W\u0142adys\u0142aw Kosiniak-Kamysz\"],\"articleSection\":[\"In Polen\"],\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/upmp.news\\\/de\\\/in-polen\\\/verteidigungsminister-nennt-prioritaeten-fuer-die-armee\\\/\",\"url\":\"https:\\\/\\\/upmp.news\\\/de\\\/in-polen\\\/verteidigungsminister-nennt-prioritaeten-fuer-die-armee\\\/\",\"name\":\"Verteidigungsminister nennt Priorit\u00e4ten f\u00fcr die Armee &#8211; U.P.M.P\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/upmp.news\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/upmp.news\\\/de\\\/in-polen\\\/verteidigungsminister-nennt-prioritaeten-fuer-die-armee\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/upmp.news\\\/de\\\/in-polen\\\/verteidigungsminister-nennt-prioritaeten-fuer-die-armee\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/upmp.news\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/Verteidigungsminister-nennt-Prioritaten-fur-die-Armee.png\",\"datePublished\":\"2024-02-09T11:02:55+00:00\",\"dateModified\":\"2024-02-09T11:02:56+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/upmp.news\\\/#\\\/schema\\\/person\\\/cebd3113030eb01f184505010f519d71\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/upmp.news\\\/de\\\/in-polen\\\/verteidigungsminister-nennt-prioritaeten-fuer-die-armee\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/upmp.news\\\/de\\\/in-polen\\\/verteidigungsminister-nennt-prioritaeten-fuer-die-armee\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/upmp.news\\\/de\\\/in-polen\\\/verteidigungsminister-nennt-prioritaeten-fuer-die-armee\\\/#primaryimage\",\"url\":\"https:\\\/\\\/upmp.news\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/Verteidigungsminister-nennt-Prioritaten-fur-die-Armee.png\",\"contentUrl\":\"https:\\\/\\\/upmp.news\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/Verteidigungsminister-nennt-Prioritaten-fur-die-Armee.png\",\"width\":938,\"height\":515,\"caption\":\"Verteidigungsminister W\u0142adys\u0142aw Kosiniak-Kamysz PAP\\\/Albert Zawada\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/upmp.news\\\/de\\\/in-polen\\\/verteidigungsminister-nennt-prioritaeten-fuer-die-armee\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/upmp.news\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Verteidigungsminister nennt Priorit\u00e4ten f\u00fcr die Armee\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/upmp.news\\\/#website\",\"url\":\"https:\\\/\\\/upmp.news\\\/\",\"name\":\"U.P.M.P\",\"description\":\"\u0423\u043a\u0440\u0430\u0457\u043d\u043e-\u043f\u043e\u043b\u044c\u0441\u044c\u043a\u0430 \u043c\u0435\u0434\u0456\u0430\u043f\u043b\u0430\u0442\u0444\u043e\u0440\u043c\u0430\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/upmp.news\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/upmp.news\\\/#\\\/schema\\\/person\\\/cebd3113030eb01f184505010f519d71\",\"name\":\"vladimyr\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/upmp.news\\\/wp-content\\\/uploads\\\/2017\\\/12\\\/ava.png\",\"url\":\"https:\\\/\\\/upmp.news\\\/wp-content\\\/uploads\\\/2017\\\/12\\\/ava.png\",\"contentUrl\":\"https:\\\/\\\/upmp.news\\\/wp-content\\\/uploads\\\/2017\\\/12\\\/ava.png\",\"caption\":\"vladimyr\"},\"url\":\"https:\\\/\\\/upmp.news\\\/de\\\/author\\\/vladimyr\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Verteidigungsminister nennt Priorit\u00e4ten f\u00fcr die Armee &#8211; U.P.M.P","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/upmp.news\/de\/in-polen\/verteidigungsminister-nennt-prioritaeten-fuer-die-armee\/","og_locale":"de_DE","og_type":"article","og_title":"Verteidigungsminister nennt Priorit\u00e4ten f\u00fcr die Armee &#8211; U.P.M.P","og_description":"Zu den wichtigsten Zielen des Ministeriums geh\u00f6re der Aufbau einer starken nationalen Gemeinschaft, die in der Lage sei, das Land zu verteidigen und in voller Alarmbereitschaft zu bleiben. Dazu habe die Regierung den h\u00f6chsten Armeehaushalt seit Jahren verabschiedet und eine Erh\u00f6hung der Geh\u00e4lter f\u00fcr Soldaten eingef\u00fchrt, teilte Polens stellvertretender Premierminister mit. Dies wird von Upmp.news [&hellip;]","og_url":"https:\/\/upmp.news\/de\/in-polen\/verteidigungsminister-nennt-prioritaeten-fuer-die-armee\/","og_site_name":"U.P.M.P","article_publisher":"https:\/\/www.facebook.com\/upmp.news\/","article_published_time":"2024-02-09T11:02:55+00:00","article_modified_time":"2024-02-09T11:02:56+00:00","og_image":[{"width":938,"height":515,"url":"https:\/\/upmp.news\/wp-content\/uploads\/2024\/02\/Verteidigungsminister-nennt-Prioritaten-fur-die-Armee.png","type":"image\/png"}],"author":"vladimyr","twitter_card":"summary_large_image","twitter_creator":"@maininua","twitter_site":"@maininua","twitter_misc":{"Verfasst von":"vladimyr","Gesch\u00e4tzte Lesezeit":"2\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/upmp.news\/de\/in-polen\/verteidigungsminister-nennt-prioritaeten-fuer-die-armee\/#article","isPartOf":{"@id":"https:\/\/upmp.news\/de\/in-polen\/verteidigungsminister-nennt-prioritaeten-fuer-die-armee\/"},"author":{"name":"vladimyr","@id":"https:\/\/upmp.news\/#\/schema\/person\/cebd3113030eb01f184505010f519d71"},"headline":"Verteidigungsminister nennt Priorit\u00e4ten f\u00fcr die Armee","datePublished":"2024-02-09T11:02:55+00:00","dateModified":"2024-02-09T11:02:56+00:00","mainEntityOfPage":{"@id":"https:\/\/upmp.news\/de\/in-polen\/verteidigungsminister-nennt-prioritaeten-fuer-die-armee\/"},"wordCount":373,"image":{"@id":"https:\/\/upmp.news\/de\/in-polen\/verteidigungsminister-nennt-prioritaeten-fuer-die-armee\/#primaryimage"},"thumbnailUrl":"https:\/\/upmp.news\/wp-content\/uploads\/2024\/02\/Verteidigungsminister-nennt-Prioritaten-fur-die-Armee.png","keywords":["Andrzej Grzyb","Micha\u0142 Dworczyk","W\u0142adys\u0142aw Kosiniak-Kamysz"],"articleSection":["In Polen"],"inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/upmp.news\/de\/in-polen\/verteidigungsminister-nennt-prioritaeten-fuer-die-armee\/","url":"https:\/\/upmp.news\/de\/in-polen\/verteidigungsminister-nennt-prioritaeten-fuer-die-armee\/","name":"Verteidigungsminister nennt Priorit\u00e4ten f\u00fcr die Armee &#8211; U.P.M.P","isPartOf":{"@id":"https:\/\/upmp.news\/#website"},"primaryImageOfPage":{"@id":"https:\/\/upmp.news\/de\/in-polen\/verteidigungsminister-nennt-prioritaeten-fuer-die-armee\/#primaryimage"},"image":{"@id":"https:\/\/upmp.news\/de\/in-polen\/verteidigungsminister-nennt-prioritaeten-fuer-die-armee\/#primaryimage"},"thumbnailUrl":"https:\/\/upmp.news\/wp-content\/uploads\/2024\/02\/Verteidigungsminister-nennt-Prioritaten-fur-die-Armee.png","datePublished":"2024-02-09T11:02:55+00:00","dateModified":"2024-02-09T11:02:56+00:00","author":{"@id":"https:\/\/upmp.news\/#\/schema\/person\/cebd3113030eb01f184505010f519d71"},"breadcrumb":{"@id":"https:\/\/upmp.news\/de\/in-polen\/verteidigungsminister-nennt-prioritaeten-fuer-die-armee\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/upmp.news\/de\/in-polen\/verteidigungsminister-nennt-prioritaeten-fuer-die-armee\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/upmp.news\/de\/in-polen\/verteidigungsminister-nennt-prioritaeten-fuer-die-armee\/#primaryimage","url":"https:\/\/upmp.news\/wp-content\/uploads\/2024\/02\/Verteidigungsminister-nennt-Prioritaten-fur-die-Armee.png","contentUrl":"https:\/\/upmp.news\/wp-content\/uploads\/2024\/02\/Verteidigungsminister-nennt-Prioritaten-fur-die-Armee.png","width":938,"height":515,"caption":"Verteidigungsminister W\u0142adys\u0142aw Kosiniak-Kamysz PAP\/Albert Zawada"},{"@type":"BreadcrumbList","@id":"https:\/\/upmp.news\/de\/in-polen\/verteidigungsminister-nennt-prioritaeten-fuer-die-armee\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/upmp.news\/"},{"@type":"ListItem","position":2,"name":"Verteidigungsminister nennt Priorit\u00e4ten f\u00fcr die Armee"}]},{"@type":"WebSite","@id":"https:\/\/upmp.news\/#website","url":"https:\/\/upmp.news\/","name":"U.P.M.P","description":"\u0423\u043a\u0440\u0430\u0457\u043d\u043e-\u043f\u043e\u043b\u044c\u0441\u044c\u043a\u0430 \u043c\u0435\u0434\u0456\u0430\u043f\u043b\u0430\u0442\u0444\u043e\u0440\u043c\u0430","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/upmp.news\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Person","@id":"https:\/\/upmp.news\/#\/schema\/person\/cebd3113030eb01f184505010f519d71","name":"vladimyr","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/upmp.news\/wp-content\/uploads\/2017\/12\/ava.png","url":"https:\/\/upmp.news\/wp-content\/uploads\/2017\/12\/ava.png","contentUrl":"https:\/\/upmp.news\/wp-content\/uploads\/2017\/12\/ava.png","caption":"vladimyr"},"url":"https:\/\/upmp.news\/de\/author\/vladimyr\/"}]}},"_links":{"self":[{"href":"https:\/\/upmp.news\/de\/wp-json\/wp\/v2\/posts\/268369","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/upmp.news\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/upmp.news\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/upmp.news\/de\/wp-json\/wp\/v2\/users\/27"}],"replies":[{"embeddable":true,"href":"https:\/\/upmp.news\/de\/wp-json\/wp\/v2\/comments?post=268369"}],"version-history":[{"count":1,"href":"https:\/\/upmp.news\/de\/wp-json\/wp\/v2\/posts\/268369\/revisions"}],"predecessor-version":[{"id":268375,"href":"https:\/\/upmp.news\/de\/wp-json\/wp\/v2\/posts\/268369\/revisions\/268375"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/upmp.news\/de\/wp-json\/wp\/v2\/media\/268370"}],"wp:attachment":[{"href":"https:\/\/upmp.news\/de\/wp-json\/wp\/v2\/media?parent=268369"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/upmp.news\/de\/wp-json\/wp\/v2\/categories?post=268369"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/upmp.news\/de\/wp-json\/wp\/v2\/tags?post=268369"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}